{"id":3622,"date":"2024-03-11T08:15:29","date_gmt":"2024-03-11T07:15:29","guid":{"rendered":"https:\/\/rafaramirez.org\/blog\/?p=3622"},"modified":"2024-03-11T10:39:42","modified_gmt":"2024-03-11T09:39:42","slug":"los-commitments-un-clasico-del-cine-musical","status":"publish","type":"post","link":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/","title":{"rendered":"Los Commitments: Un cl\u00e1sico del cine musical."},"content":{"rendered":"<p>Hoy os hablo de la pel\u00edcula de Alan Parker: Los Commitments, un film musical de 1991, cuya banda sonora fue un \u00e9xito en Reino Unido y Estados Unidos, consiguiendo un Grammy y varios Globos de Oro. Pel\u00edcula cargada de energ\u00eda, buena m\u00fasica y humor que no deber\u00edais dejar de ver.<\/p>\n<figure id=\"attachment_3627\" aria-describedby=\"caption-attachment-3627\" style=\"width: 206px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3627 size-medium\" src=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster-206x300.jpg\" alt=\"Alan Parker: Los Commitments (1991).\" width=\"206\" height=\"300\" srcset=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster-206x300.jpg 206w, https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster-705x1024.jpg 705w, https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster-768x1116.jpg 768w, https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster-1057x1536.jpg 1057w, https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/Los_commitments_poster.jpg 1101w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a><figcaption id=\"caption-attachment-3627\" class=\"wp-caption-text\">Alan Parker: Los Commitments (1991).<\/figcaption><\/figure>\n<p data-sourcepos=\"9:1-9:21\"><strong>Historia y gui\u00f3n:<\/strong><\/p>\n<p data-sourcepos=\"11:1-11:558\">Basada en la novela hom\u00f3nima de Roddy Doyle, la pel\u00edcula narra la historia de Jimmy Rabbitte (Robert Arkins), un joven desempleado de Dubl\u00edn con una pasi\u00f3n por la m\u00fasica soul. Decide formar una banda con otros j\u00f3venes de su clase social, a pesar de que ninguno de ellos tiene experiencia musical previa. A trav\u00e9s de un proceso de audiciones, Jimmy re\u00fane a un grupo heterog\u00e9neo de personajes con talento, incluyendo a la talentosa cantante Deco (Angeline Ball), el guitarrista Outspan (Glen Hansard) y el bajista Joey \u00abThe Lips\u00bb Fagan (Johnny Murphy). A pesar de las dificultades y los conflictos internos, la banda logra encontrar su propio sonido y alcanzar el \u00e9xito.<\/p>\n<p data-sourcepos=\"13:1-13:180\">El guion de Dick Clement y Roddy Doyle captura a la perfecci\u00f3n la energ\u00eda y el humor de la novela original, y crea personajes memorables con los que el p\u00fablico puede identificarse.<\/p>\n<p data-sourcepos=\"48:1-48:17\"><strong>Banda sonora:<\/strong><\/p>\n<p data-sourcepos=\"50:1-50:226\">La banda sonora de Los Commitments fue un \u00e9xito comercial y de cr\u00edtica. El \u00e1lbum alcanz\u00f3 el n\u00famero 1 en las listas de \u00e9xitos del Reino Unido y los Estados Unidos, y gan\u00f3 el premio Grammy al Mejor \u00c1lbum de Soul\/R&amp;B en 1992.<\/p>\n<p data-sourcepos=\"19:1-19:26\"><strong>Elogios de la cr\u00edtica:<\/strong><\/p>\n<p data-sourcepos=\"21:1-21:218\">Los Commitments fue aclamada por la cr\u00edtica por su humor, su energ\u00eda y su retrato realista de la vida de la clase trabajadora en Dubl\u00edn. La pel\u00edcula fue elogiada por su direcci\u00f3n, su guion, su m\u00fasica y sus actuaciones.<\/p>\n<p data-sourcepos=\"3:1-3:12\"><strong>Premios:<\/strong><\/p>\n<ul data-sourcepos=\"5:1-8:0\">\n<li data-sourcepos=\"5:1-5:409\"><strong>Premios BAFTA 1991:<\/strong>\u00a0Ganadora de Mejor Pel\u00edcula, Mejor Director (Alan Parker), Mejor Guion Adaptado (Dick Clement y Roddy Doyle) y Mejor Montaje (Gerry Hambling). Nominada a Mejor Actor de Reparto (Robert Arkins), Mejor Actriz de Reparto (Angeline Ball), Mejor Fotograf\u00eda (Roger Deakins), Mejor Dise\u00f1o de Producci\u00f3n (Stuart Craig) y Mejor Sonido (John Downer, Chris Jenkins, Gerry Humphreys y Tony Dawe).<\/li>\n<li data-sourcepos=\"6:1-6:129\"><strong>Premios Globo de Oro 1992:<\/strong> Nominada a Mejor Pel\u00edcula &#8211; Comedia o Musical y Mejor Actor (Robert Arkins).<\/li>\n<li data-sourcepos=\"7:1-8:0\"><strong>Premios Oscar 1992:<\/strong>\u00a0Nominada a Mejor Canci\u00f3n Original (\u00abIn the Midnight Hour\u00bb).<\/li>\n<\/ul>\n<p data-sourcepos=\"23:1-23:16\"><strong>Alan Parker:<\/strong><\/p>\n<figure id=\"attachment_3628\" aria-describedby=\"caption-attachment-3628\" style=\"width: 209px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3628 size-medium\" src=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/alanparker_portrait-209x300.jpg\" alt=\"Alan Parker (1944-2020).\" width=\"209\" height=\"300\" srcset=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/alanparker_portrait-209x300.jpg 209w, https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/alanparker_portrait.jpg 348w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><figcaption id=\"caption-attachment-3628\" class=\"wp-caption-text\">Alan Parker (1944-2020).<\/figcaption><\/figure>\n<p data-sourcepos=\"25:1-25:259\">El director Alan Parker es conocido por su trabajo en pel\u00edculas como \u00abExpreso de Medianoche\u00bb, \u00abMississippi Burning\u00bb y \u00abEvita\u00bb. Parker aporta su talento a Los Commitments, creando una pel\u00edcula vibrante y llena de vida que captura el esp\u00edritu de la m\u00fasica soul.<\/p>\n<p data-sourcepos=\"3:1-3:226\">Fue un aclamado director, guionista y productor de cine brit\u00e1nico. Reconocido por su versatilidad y su ojo para el talento, dej\u00f3 una huella profunda en la industria cinematogr\u00e1fica.<\/p>\n<ul data-sourcepos=\"7:1-11:0\">\n<li data-sourcepos=\"7:1-7:82\">Inici\u00f3 su carrera en publicidad y televisi\u00f3n, dirigiendo anuncios y comerciales.<\/li>\n<li data-sourcepos=\"8:1-8:66\">Debut\u00f3 en el cine en 1976 con la comedia musical \u00abBugsy Malone\u00bb.<\/li>\n<li data-sourcepos=\"9:1-9:167\">A lo largo de su trayectoria, explor\u00f3 diversos g\u00e9neros, desde musicales como \u00abFame\u00bb y \u00abEvita\u00bb hasta dramas como \u00abMississippi Burning\u00bb y thrillers como \u00abAngel Heart\u00bb.<\/li>\n<li data-sourcepos=\"10:1-11:0\">Tambi\u00e9n dirigi\u00f3 pel\u00edculas basadas en hechos reales, como \u00abExpreso de medianoche\u00bb y \u00abAngela&#8217;s Ashes\u00bb.<\/li>\n<\/ul>\n<p>Sus pel\u00edculas obtuvieron numerosos premios, incluyendo 19 premios BAFTA, 10 Globos de Oro y 10 nominaciones a los premios Oscar. Recibi\u00f3 el CBE (Comandante de la Orden del Imperio Brit\u00e1nico) en 1995 y fue nombrado caballero en 2002.<\/p>\n<p data-sourcepos=\"17:1-17:11\">Su estilo visual distintivo y su habilidad para narrar historias conmovedoras y complejas lo convirtieron en un director de renombre. Contribuy\u00f3 al reconocimiento del talento brit\u00e1nico, tanto delante como detr\u00e1s de las c\u00e1maras. Pel\u00edculas como \u00abLos Commitments\u00bb y \u00abThe Wall\u00bb de Pink Floyd contin\u00faan siendo cl\u00e1sicos del cine.<\/p>\n<p data-sourcepos=\"27:1-27:15\"><strong>En resumen:<\/strong><\/p>\n<p data-sourcepos=\"29:1-29:223\">Los Commitments es una pel\u00edcula cl\u00e1sica que combina humor, drama y m\u00fasica para crear una experiencia cinematogr\u00e1fica inolvidable. La pel\u00edcula es un homenaje a la m\u00fasica soul y a la cultura de la clase trabajadora en Dubl\u00edn.<\/p>\n<p>Espero que os guste la pel\u00edcula, no dej\u00e9is de verla. Puedes dejar tus comentarios debajo del post. \u00a1Saludos!<\/p>\n<p style=\"text-align: left;\"><strong>Trailer en ingl\u00e9s de Los Commitments:<\/strong><\/p>\n<p style=\"text-align: left;\" data-sourcepos=\"29:1-29:223\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/VSXGeUQc0Co?si=Wkjj1FLHjlYxW20q\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p data-sourcepos=\"31:1-31:25\"><strong>M\u00e1s informaci\u00f3n:<\/strong><\/p>\n<ul data-sourcepos=\"33:1-35:106\">\n<li data-sourcepos=\"33:1-33:62\">Wikipedia Los Commitments: <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/The_Commitments_(pel%C3%ADcula)\" target=\"_blank\" rel=\"noopener\">https:\/\/es.wikipedia.org\/wiki\/The_Commitments_(pel%C3%ADcula)<\/a><\/strong><\/li>\n<li data-sourcepos=\"34:1-34:134\">Filmaffinity Los Commitments:\u00a0<strong><a class=\"traceable-link\" href=\"https:\/\/www.filmaffinity.com\/es\/film720819.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.filmaffinity.com\/es\/film720819.html<\/a><\/strong><\/li>\n<li data-sourcepos=\"35:1-35:106\">IMDb Los Commitments:<strong><a class=\"traceable-link\" href=\"https:\/\/www.imdb.com\/title\/tt0101605\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.imdb.com\/title\/tt0101605<\/a><\/strong><\/li>\n<li data-sourcepos=\"35:1-35:106\">Comprar la pel\u00edcula en Amazon: <a href=\"https:\/\/www.amazon.es\/Commitments-Edici%C3%B3n-Especial-DVD\/dp\/B01LBQC982\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.amazon.es\/Commitments-Edici%C3%B3n-Especial-DVD\/dp\/B01LBQC982\/<\/a><\/li>\n<li data-sourcepos=\"38:1-38:146\">Puedes encontrar informaci\u00f3n detallada sobre la vida y filmograf\u00eda de Alan Parker en su p\u00e1gina web oficial: <a class=\"traceable-link\" href=\"https:\/\/alanparker.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/alanparker.com\/<\/a>.<\/li>\n<li data-sourcepos=\"39:1-39:138\">Tambi\u00e9n puedes consultar su perfil en Wikipedia:\u00a0<a class=\"traceable-link\" href=\"https:\/\/es.wikipedia.org\/wiki\/Alan_Parker\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/es.wikipedia.org\/wiki\/Alan_Parker<\/a>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy os hablo de la pel\u00edcula de Alan Parker: Los Commitments, un film musical de 1991, cuya banda sonora fue un \u00e9xito en Reino Unido y Estados Unidos, consiguiendo un Grammy y varios Globos de Oro. Pel\u00edcula cargada de energ\u00eda, buena m\u00fasica y humor que no deber\u00edais dejar de ver. Historia y gui\u00f3n: Basada en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3630,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[711],"tags":[1203,944,1200,1219,1204,68,899,900,761,762,1222,168,1220,1215,1221,1201,1212,1213,1214,1211,1206,1205,897,359,1207,1210,1209,1208,1216,1218,1217,1202],"class_list":["post-3622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine","tag-1203","tag-944","tag-alan-parker","tag-angeline-ball","tag-biografia-de-alan-parker","tag-blog-de-rafael-ramirez","tag-cine-clasico","tag-clasicos-de-cine","tag-clasicos-del-cine","tag-critica-de-cine","tag-dick-clement","tag-estados-unidos","tag-glen-hansard","tag-grammy-al-mejor-album-de-soul","tag-johnny-murphy","tag-los-commitments","tag-mejor-director","tag-mejor-guion-adaptado","tag-mejor-montaje","tag-mejor-pelicula","tag-musicales","tag-pelicula-musical","tag-pelicula-recomendada","tag-peliculas","tag-peliculas-con-grammy","tag-premios-bafta-1991","tag-premios-globo-de-oro-1992","tag-premios-oscar-1992","tag-reino-unido","tag-robert-arkins","tag-roddy-doyle","tag-the-commitments"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez\" \/>\n<meta property=\"og:description\" content=\"Hoy os hablo de la pel\u00edcula de Alan Parker: Los Commitments, un film musical de 1991, cuya banda sonora fue un \u00e9xito en Reino Unido y Estados Unidos, consiguiendo un Grammy y varios Globos de Oro. Pel\u00edcula cargada de energ\u00eda, buena m\u00fasica y humor que no deber\u00edais dejar de ver. Historia y gui\u00f3n: Basada en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Rafael Ram\u00edrez\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T07:15:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T09:39:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ram\u00edrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rafaramirez_ok\" \/>\n<meta name=\"twitter:site\" content=\"@rafaramirez_ok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ram\u00edrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/\"},\"author\":{\"name\":\"Rafael Ram\u00edrez\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"headline\":\"Los Commitments: Un cl\u00e1sico del cine musical.\",\"datePublished\":\"2024-03-11T07:15:29+00:00\",\"dateModified\":\"2024-03-11T09:39:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/\"},\"wordCount\":832,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"image\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/the_commitments_banner_ok.jpg\",\"keywords\":[\"1991\",\"1992\",\"Alan Parker\",\"Angeline Ball\",\"biograf\u00eda de Alan Parker\",\"blog de Rafael Ram\u00edrez\",\"cine cl\u00e1sico\",\"cl\u00e1sicos de cine\",\"cl\u00e1sicos del cine\",\"cr\u00edtica de cine\",\"Dick Clement\",\"Estados Unidos\",\"Glen Hansard\",\"Grammy al Mejor \u00c1lbum de Soul\",\"Johnny Murphy\",\"Los Commitments\",\"Mejor Director\",\"Mejor Guion Adaptado\",\"Mejor Montaje\",\"Mejor Pel\u00edcula\",\"musicales\",\"pel\u00edcula musical\",\"pel\u00edcula recomendada\",\"pel\u00edculas\",\"pel\u00edculas con grammy\",\"Premios BAFTA 1991\",\"Premios Globo de Oro 1992\",\"Premios Oscar 1992\",\"Reino Unido\",\"Robert Arkins\",\"Roddy Doyle\",\"The Commitments\"],\"articleSection\":[\"Cine\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/\",\"name\":\"Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/the_commitments_banner_ok.jpg\",\"datePublished\":\"2024-03-11T07:15:29+00:00\",\"dateModified\":\"2024-03-11T09:39:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/the_commitments_banner_ok.jpg\",\"contentUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/the_commitments_banner_ok.jpg\",\"width\":850,\"height\":456,\"caption\":\"Alan Parker: Los Commitments (1991).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/03\\\/11\\\/los-commitments-un-clasico-del-cine-musical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Commitments: Un cl\u00e1sico del cine musical.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/\",\"name\":\"Blog de Rafael Ram\u00edrez\",\"description\":\"Un sitio social, de arte y cultura\",\"publisher\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\",\"name\":\"Rafael Ram\u00edrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"contentUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"width\":600,\"height\":606,\"caption\":\"Rafael Ram\u00edrez\"},\"logo\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.rafaramirez.org\\\/blog\",\"https:\\\/\\\/www.instagram.com\\\/rafaramirez_ok\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/Ramirez_Rafa\\\/\",\"https:\\\/\\\/x.com\\\/rafaramirez_ok\"],\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/author\\\/rafaell_qm6j97da\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/","og_locale":"es_ES","og_type":"article","og_title":"Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez","og_description":"Hoy os hablo de la pel\u00edcula de Alan Parker: Los Commitments, un film musical de 1991, cuya banda sonora fue un \u00e9xito en Reino Unido y Estados Unidos, consiguiendo un Grammy y varios Globos de Oro. Pel\u00edcula cargada de energ\u00eda, buena m\u00fasica y humor que no deber\u00edais dejar de ver. Historia y gui\u00f3n: Basada en [&hellip;]","og_url":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/","og_site_name":"Blog de Rafael Ram\u00edrez","article_published_time":"2024-03-11T07:15:29+00:00","article_modified_time":"2024-03-11T09:39:42+00:00","og_image":[{"width":850,"height":456,"url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","type":"image\/jpeg"}],"author":"Rafael Ram\u00edrez","twitter_card":"summary_large_image","twitter_creator":"@rafaramirez_ok","twitter_site":"@rafaramirez_ok","twitter_misc":{"Escrito por":"Rafael Ram\u00edrez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#article","isPartOf":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/"},"author":{"name":"Rafael Ram\u00edrez","@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"headline":"Los Commitments: Un cl\u00e1sico del cine musical.","datePublished":"2024-03-11T07:15:29+00:00","dateModified":"2024-03-11T09:39:42+00:00","mainEntityOfPage":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/"},"wordCount":832,"commentCount":0,"publisher":{"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"image":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","keywords":["1991","1992","Alan Parker","Angeline Ball","biograf\u00eda de Alan Parker","blog de Rafael Ram\u00edrez","cine cl\u00e1sico","cl\u00e1sicos de cine","cl\u00e1sicos del cine","cr\u00edtica de cine","Dick Clement","Estados Unidos","Glen Hansard","Grammy al Mejor \u00c1lbum de Soul","Johnny Murphy","Los Commitments","Mejor Director","Mejor Guion Adaptado","Mejor Montaje","Mejor Pel\u00edcula","musicales","pel\u00edcula musical","pel\u00edcula recomendada","pel\u00edculas","pel\u00edculas con grammy","Premios BAFTA 1991","Premios Globo de Oro 1992","Premios Oscar 1992","Reino Unido","Robert Arkins","Roddy Doyle","The Commitments"],"articleSection":["Cine"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/","url":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/","name":"Los Commitments: Un cl\u00e1sico del cine musical. - Blog de Rafael Ram\u00edrez","isPartOf":{"@id":"https:\/\/rafaramirez.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#primaryimage"},"image":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","datePublished":"2024-03-11T07:15:29+00:00","dateModified":"2024-03-11T09:39:42+00:00","breadcrumb":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#primaryimage","url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","contentUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","width":850,"height":456,"caption":"Alan Parker: Los Commitments (1991)."},{"@type":"BreadcrumbList","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/03\/11\/los-commitments-un-clasico-del-cine-musical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rafaramirez.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Los Commitments: Un cl\u00e1sico del cine musical."}]},{"@type":"WebSite","@id":"https:\/\/rafaramirez.org\/blog\/#website","url":"https:\/\/rafaramirez.org\/blog\/","name":"Blog de Rafael Ram\u00edrez","description":"Un sitio social, de arte y cultura","publisher":{"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rafaramirez.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5","name":"Rafael Ram\u00edrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","contentUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","width":600,"height":606,"caption":"Rafael Ram\u00edrez"},"logo":{"@id":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg"},"sameAs":["https:\/\/www.rafaramirez.org\/blog","https:\/\/www.instagram.com\/rafaramirez_ok\/","https:\/\/es.pinterest.com\/Ramirez_Rafa\/","https:\/\/x.com\/rafaramirez_ok"],"url":"https:\/\/rafaramirez.org\/blog\/index.php\/author\/rafaell_qm6j97da\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/03\/the_commitments_banner_ok.jpg","_links":{"self":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3622"}],"version-history":[{"count":15,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3622\/revisions"}],"predecessor-version":[{"id":3672,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3622\/revisions\/3672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/media\/3630"}],"wp:attachment":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}