{"id":1075,"date":"2024-02-02T08:30:46","date_gmt":"2024-02-02T07:30:46","guid":{"rendered":"http:\/\/blog.rafaramirez.org\/?p=1075"},"modified":"2026-02-02T14:09:57","modified_gmt":"2026-02-02T13:09:57","slug":"estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas","status":"publish","type":"post","link":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/","title":{"rendered":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves?"},"content":{"rendered":"<p>Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.<\/p>\n<p>Estos libros fueron un gran \u00e9xito editorial. Nos permit\u00edan ver fant\u00e1sticas vistas tridimensionales sin necesidad de usar gafas y descubrir im\u00e1genes ocultas en ellas.<\/p>\n<p>Os dejo algunas de estas im\u00e1genes para que redescubr\u00e1is esta maravillosa experiencia.<\/p>\n<blockquote><p><em><strong>\u00bfC\u00f3mo funciona esto?<\/strong> <\/em>Es sencillo pero necesita de\u00a0un poco de pr\u00e1ctica.<br \/>\n&#8211; Acerca la nariz a la foto y mant\u00e9n la mirada fija en un punto.<br \/>\n&#8211;\u00a0Ahora ve\u00a0alej\u00e1ndote poco a poco hasta que llegue el momento en el\u00a0que puedas ver n\u00edtidamente la imagen tridimensional.<br \/>\n&#8211; Mueve los ojos ahora para observar toda la imagen y descubrir la\u00a0figura oculta.<\/p><\/blockquote>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/fc04.deviantart.net\/fs11\/i\/2006\/175\/7\/6\/Africa_3D_Stereogram_by_3Dimka.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/fc04.deviantart.net\/fs11\/i\/2006\/175\/7\/6\/Africa_3D_Stereogram_by_3Dimka.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/41.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"800\" height=\"640\" \/><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.med39.ru\/sirds\/32.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/32.jpg\" alt=\"Imagen estereosc\u00f3pica 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1040px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.med39.ru\/sirds\/33.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/33.jpg\" alt=\"Imagen estereosc\u00f3pica 3D. Blog de Rafael Ram\u00edrez\" width=\"1040\" height=\"825\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/farm3.static.flickr.com\/2048\/1989282016_0ce7e9dde7_o.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2048\/1989282016_0ce7e9dde7_o.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/34.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/41.media.tumblr.com\/daa526f666232c357a3e20bf68aa378d\/tumblr_moecug7KL41s63n3ho2_1280.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/41.media.tumblr.com\/daa526f666232c357a3e20bf68aa378d\/tumblr_moecug7KL41s63n3ho2_1280.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/38.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"900\" height=\"675\" \/><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.med39.ru\/sirds\/29.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.med39.ru\/sirds\/29.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"716\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<figure style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.med39.ru\/sirds\/10.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.med39.ru\/sirds\/10.jpg\" alt=\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\" width=\"1024\" height=\"768\" \/><\/a><figcaption class=\"wp-caption-text\">Clic sobre la imagen para ver a tama\u00f1o completo<\/figcaption><\/figure>\n<p><strong>Fuentes:<\/strong><br \/>\n<a href=\"https:\/\/www.google.com\/search?q=3d+stereogram+free\" target=\"_blank\" rel=\"noopener\">1.Estereogramas en Google<\/a><br \/>\n<a href=\"https:\/\/www.med39.ru\/sirds\/\" target=\"_blank\" rel=\"noopener\">2.Med39<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador. Estos libros fueron un gran \u00e9xito editorial. Nos permit\u00edan ver fant\u00e1sticas vistas tridimensionales sin necesidad de usar gafas y descubrir im\u00e1genes ocultas en ellas. Os dejo algunas de estas im\u00e1genes para que redescubr\u00e1is esta maravillosa experiencia. \u00bfC\u00f3mo funciona esto? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[784,785,68,139,174,781,782,783],"class_list":["post-1075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografia","tag-3d","tag-3d-sin-gafas","tag-blog-de-rafael-ramirez","tag-destacado","tag-estereogramas-3d","tag-imagenes-3d","tag-imagenes-ocultas","tag-imagenes-tridimensionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez<\/title>\n<meta name=\"description\" content=\"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez\" \/>\n<meta property=\"og:description\" content=\"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Rafael Ram\u00edrez\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T07:30:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T13:09:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ram\u00edrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rafaramirez_ok\" \/>\n<meta name=\"twitter:site\" content=\"@rafaramirez_ok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ram\u00edrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/\"},\"author\":{\"name\":\"Rafael Ram\u00edrez\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"headline\":\"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves?\",\"datePublished\":\"2024-02-02T07:30:46+00:00\",\"dateModified\":\"2026-02-02T13:09:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"image\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/3D_stereoscopic_banner_logblog.jpg\",\"keywords\":[\"3D\",\"3D sin gafas\",\"blog de Rafael Ram\u00edrez\",\"destacado\",\"Estereogramas 3D\",\"im\u00e1genes 3D\",\"im\u00e1genes ocultas\",\"im\u00e1genes tridimensionales\"],\"articleSection\":[\"Fotograf\u00eda &amp; Arte digital\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/\",\"name\":\"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/3D_stereoscopic_banner_logblog.jpg\",\"datePublished\":\"2024-02-02T07:30:46+00:00\",\"dateModified\":\"2026-02-02T13:09:57+00:00\",\"description\":\"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/3D_stereoscopic_banner_logblog.jpg\",\"contentUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/3D_stereoscopic_banner_logblog.jpg\",\"width\":600,\"height\":450,\"caption\":\"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/2024\\\/02\\\/02\\\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/\",\"name\":\"Blog de Rafael Ram\u00edrez\",\"description\":\"Un sitio social, de arte y cultura\",\"publisher\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/#\\\/schema\\\/person\\\/50f43b6d60c578760d4c17bda54ab6a5\",\"name\":\"Rafael Ram\u00edrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"contentUrl\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\",\"width\":600,\"height\":606,\"caption\":\"Rafael Ram\u00edrez\"},\"logo\":{\"@id\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RR_socialnetwork.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.rafaramirez.org\\\/blog\",\"https:\\\/\\\/www.instagram.com\\\/rafaramirez_ok\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/Ramirez_Rafa\\\/\",\"https:\\\/\\\/x.com\\\/rafaramirez_ok\"],\"url\":\"https:\\\/\\\/rafaramirez.org\\\/blog\\\/index.php\\\/author\\\/rafaell_qm6j97da\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez","description":"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/","og_locale":"es_ES","og_type":"article","og_title":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez","og_description":"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.","og_url":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/","og_site_name":"Blog de Rafael Ram\u00edrez","article_published_time":"2024-02-02T07:30:46+00:00","article_modified_time":"2026-02-02T13:09:57+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","type":"image\/jpeg"}],"author":"Rafael Ram\u00edrez","twitter_card":"summary_large_image","twitter_creator":"@rafaramirez_ok","twitter_site":"@rafaramirez_ok","twitter_misc":{"Escrito por":"Rafael Ram\u00edrez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#article","isPartOf":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/"},"author":{"name":"Rafael Ram\u00edrez","@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"headline":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves?","datePublished":"2024-02-02T07:30:46+00:00","dateModified":"2026-02-02T13:09:57+00:00","mainEntityOfPage":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"image":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#primaryimage"},"thumbnailUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","keywords":["3D","3D sin gafas","blog de Rafael Ram\u00edrez","destacado","Estereogramas 3D","im\u00e1genes 3D","im\u00e1genes ocultas","im\u00e1genes tridimensionales"],"articleSection":["Fotograf\u00eda &amp; Arte digital"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/","url":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/","name":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves? - Blog de Rafael Ram\u00edrez","isPartOf":{"@id":"https:\/\/rafaramirez.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#primaryimage"},"image":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#primaryimage"},"thumbnailUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","datePublished":"2024-02-02T07:30:46+00:00","dateModified":"2026-02-02T13:09:57+00:00","description":"Hace algunos a\u00f1os se publicaron los primeros libros de estereogramas con im\u00e1genes 3D generadas por ordenador.","breadcrumb":{"@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#primaryimage","url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","contentUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","width":600,"height":450,"caption":"Im\u00e1genes estereosc\u00f3picas 3D. Blog de Rafael Ram\u00edrez"},{"@type":"BreadcrumbList","@id":"https:\/\/rafaramirez.org\/blog\/index.php\/2024\/02\/02\/estereogramas-3d-descubre-lo-que-ocultan-sin-necesidad-de-gafas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rafaramirez.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Estereogramas 3D, descubre lo que ocultan. \u00bfTe atreves?"}]},{"@type":"WebSite","@id":"https:\/\/rafaramirez.org\/blog\/#website","url":"https:\/\/rafaramirez.org\/blog\/","name":"Blog de Rafael Ram\u00edrez","description":"Un sitio social, de arte y cultura","publisher":{"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rafaramirez.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/rafaramirez.org\/blog\/#\/schema\/person\/50f43b6d60c578760d4c17bda54ab6a5","name":"Rafael Ram\u00edrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","contentUrl":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg","width":600,"height":606,"caption":"Rafael Ram\u00edrez"},"logo":{"@id":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/09\/RR_socialnetwork.jpg"},"sameAs":["https:\/\/www.rafaramirez.org\/blog","https:\/\/www.instagram.com\/rafaramirez_ok\/","https:\/\/es.pinterest.com\/Ramirez_Rafa\/","https:\/\/x.com\/rafaramirez_ok"],"url":"https:\/\/rafaramirez.org\/blog\/index.php\/author\/rafaell_qm6j97da\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/rafaramirez.org\/blog\/wp-content\/uploads\/2024\/02\/3D_stereoscopic_banner_logblog.jpg","_links":{"self":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":15,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"predecessor-version":[{"id":11876,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1075\/revisions\/11876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/media\/3213"}],"wp:attachment":[{"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rafaramirez.org\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}